{"id":20837,"date":"2024-07-21T15:19:30","date_gmt":"2024-07-21T19:19:30","guid":{"rendered":"https:\/\/hebdo24.com\/wp-content\/uploads\/2024\/07\/Les-400-Mawozo-incendient-le-commissariat-de-Ganthier-defiant-le-Gouvernement-et-la-PNH.JPEG"},"modified":"2024-07-21T15:19:30","modified_gmt":"2024-07-21T19:19:30","slug":"les-400-mawozo-incendient-le-commissariat-de-ganthier-defiant-le-gouvernement-et-la-pnh-3","status":"inherit","type":"attachment","link":"https:\/\/hebdo24.com\/en\/les-400-mawozo-incendient-le-commissariat-de-ganthier-defiant-le-gouvernement-et-la-pnh-3\/","title":{"rendered":"Les 400 Mawozo incendient le commissariat de Ganthier d\u00e9fiant le Gouvernement et la PNH"},"author":31,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":[],"class_list":["post-20837","attachment","type-attachment","status-inherit"],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/hebdo24.com\/wp-content\/uploads\/2024\/07\/Les-400-Mawozo-incendient-le-commissariat-de-Ganthier-defiant-le-Gouvernement-et-la-PNH.JPEG'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/hebdo24.com\/wp-content\/uploads\/2024\/07\/Les-400-Mawozo-incendient-le-commissariat-de-Ganthier-defiant-le-Gouvernement-et-la-PNH-300x200.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/hebdo24.com\/wp-content\/uploads\/2024\/07\/Les-400-Mawozo-incendient-le-commissariat-de-Ganthier-defiant-le-Gouvernement-et-la-PNH-300x200.jpeg 300w, https:\/\/hebdo24.com\/wp-content\/uploads\/2024\/07\/Les-400-Mawozo-incendient-le-commissariat-de-Ganthier-defiant-le-Gouvernement-et-la-PNH-768x511.jpeg 768w, https:\/\/hebdo24.com\/wp-content\/uploads\/2024\/07\/Les-400-Mawozo-incendient-le-commissariat-de-Ganthier-defiant-le-Gouvernement-et-la-PNH-750x500.jpeg 750w, https:\/\/hebdo24.com\/wp-content\/uploads\/2024\/07\/Les-400-Mawozo-incendient-le-commissariat-de-Ganthier-defiant-le-Gouvernement-et-la-PNH.JPEG 1000w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>Les \u00ab\u00a0400 Mawozo\u00a0\u00bb incendient le commissariat de Ganthier, d\u00e9fiant le Gouvernement et la PNH<\/p>\n"},"caption":{"rendered":"<p>Les \u00ab\u00a0400 Mawozo\u00a0\u00bb incendient le commissariat de Ganthier, d\u00e9fiant le Gouvernement et la PNH<\/p>\n"},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1000,"height":666,"file":"2024\/07\/Les-400-Mawozo-incendient-le-commissariat-de-Ganthier-defiant-le-Gouvernement-et-la-PNH.JPEG","filesize":131014,"sizes":{"medium":{"file":"Les-400-Mawozo-incendient-le-commissariat-de-Ganthier-defiant-le-Gouvernement-et-la-PNH-300x200.jpeg","width":300,"height":200,"filesize":15825,"mime_type":"image\/jpeg","source_url":"https:\/\/hebdo24.com\/wp-content\/uploads\/2024\/07\/Les-400-Mawozo-incendient-le-commissariat-de-Ganthier-defiant-le-Gouvernement-et-la-PNH-300x200.jpeg"},"thumbnail":{"file":"Les-400-Mawozo-incendient-le-commissariat-de-Ganthier-defiant-le-Gouvernement-et-la-PNH-150x150.jpeg","width":150,"height":150,"filesize":7798,"mime_type":"image\/jpeg","source_url":"https:\/\/hebdo24.com\/wp-content\/uploads\/2024\/07\/Les-400-Mawozo-incendient-le-commissariat-de-Ganthier-defiant-le-Gouvernement-et-la-PNH-150x150.jpeg"},"medium_large":{"file":"Les-400-Mawozo-incendient-le-commissariat-de-Ganthier-defiant-le-Gouvernement-et-la-PNH-768x511.jpeg","width":768,"height":511,"filesize":59590,"mime_type":"image\/jpeg","source_url":"https:\/\/hebdo24.com\/wp-content\/uploads\/2024\/07\/Les-400-Mawozo-incendient-le-commissariat-de-Ganthier-defiant-le-Gouvernement-et-la-PNH-768x511.jpeg"},"jnews-360x180":{"file":"Les-400-Mawozo-incendient-le-commissariat-de-Ganthier-defiant-le-Gouvernement-et-la-PNH-360x180.jpeg","width":360,"height":180,"filesize":15097,"mime_type":"image\/jpeg","source_url":"https:\/\/hebdo24.com\/wp-content\/uploads\/2024\/07\/Les-400-Mawozo-incendient-le-commissariat-de-Ganthier-defiant-le-Gouvernement-et-la-PNH-360x180.jpeg"},"jnews-750x375":{"file":"Les-400-Mawozo-incendient-le-commissariat-de-Ganthier-defiant-le-Gouvernement-et-la-PNH-750x375.jpeg","width":750,"height":375,"filesize":41236,"mime_type":"image\/jpeg","source_url":"https:\/\/hebdo24.com\/wp-content\/uploads\/2024\/07\/Les-400-Mawozo-incendient-le-commissariat-de-Ganthier-defiant-le-Gouvernement-et-la-PNH-750x375.jpeg"},"jnews-1140x570":{"file":"Les-400-Mawozo-incendient-le-commissariat-de-Ganthier-defiant-le-Gouvernement-et-la-PNH-1000x570.jpeg","width":1000,"height":570,"filesize":77977,"mime_type":"image\/jpeg","source_url":"https:\/\/hebdo24.com\/wp-content\/uploads\/2024\/07\/Les-400-Mawozo-incendient-le-commissariat-de-Ganthier-defiant-le-Gouvernement-et-la-PNH-1000x570.jpeg"},"jnews-120x86":{"file":"Les-400-Mawozo-incendient-le-commissariat-de-Ganthier-defiant-le-Gouvernement-et-la-PNH-120x86.jpeg","width":120,"height":86,"filesize":4660,"mime_type":"image\/jpeg","source_url":"https:\/\/hebdo24.com\/wp-content\/uploads\/2024\/07\/Les-400-Mawozo-incendient-le-commissariat-de-Ganthier-defiant-le-Gouvernement-et-la-PNH-120x86.jpeg"},"jnews-350x250":{"file":"Les-400-Mawozo-incendient-le-commissariat-de-Ganthier-defiant-le-Gouvernement-et-la-PNH-350x250.jpeg","width":350,"height":250,"filesize":20765,"mime_type":"image\/jpeg","source_url":"https:\/\/hebdo24.com\/wp-content\/uploads\/2024\/07\/Les-400-Mawozo-incendient-le-commissariat-de-Ganthier-defiant-le-Gouvernement-et-la-PNH-350x250.jpeg"},"jnews-750x536":{"file":"Les-400-Mawozo-incendient-le-commissariat-de-Ganthier-defiant-le-Gouvernement-et-la-PNH-750x536.jpeg","width":750,"height":536,"filesize":59882,"mime_type":"image\/jpeg","source_url":"https:\/\/hebdo24.com\/wp-content\/uploads\/2024\/07\/Les-400-Mawozo-incendient-le-commissariat-de-Ganthier-defiant-le-Gouvernement-et-la-PNH-750x536.jpeg"},"jnews-360x504":{"file":"Les-400-Mawozo-incendient-le-commissariat-de-Ganthier-defiant-le-Gouvernement-et-la-PNH-360x504.jpeg","width":360,"height":504,"filesize":29875,"mime_type":"image\/jpeg","source_url":"https:\/\/hebdo24.com\/wp-content\/uploads\/2024\/07\/Les-400-Mawozo-incendient-le-commissariat-de-Ganthier-defiant-le-Gouvernement-et-la-PNH-360x504.jpeg"},"jnews-75x75":{"file":"Les-400-Mawozo-incendient-le-commissariat-de-Ganthier-defiant-le-Gouvernement-et-la-PNH-75x75.jpeg","width":75,"height":75,"filesize":3355,"mime_type":"image\/jpeg","source_url":"https:\/\/hebdo24.com\/wp-content\/uploads\/2024\/07\/Les-400-Mawozo-incendient-le-commissariat-de-Ganthier-defiant-le-Gouvernement-et-la-PNH-75x75.jpeg"},"jnews-350x350":{"file":"Les-400-Mawozo-incendient-le-commissariat-de-Ganthier-defiant-le-Gouvernement-et-la-PNH-350x350.jpeg","width":350,"height":350,"filesize":25090,"mime_type":"image\/jpeg","source_url":"https:\/\/hebdo24.com\/wp-content\/uploads\/2024\/07\/Les-400-Mawozo-incendient-le-commissariat-de-Ganthier-defiant-le-Gouvernement-et-la-PNH-350x350.jpeg"},"jnews-featured-750":{"file":"Les-400-Mawozo-incendient-le-commissariat-de-Ganthier-defiant-le-Gouvernement-et-la-PNH-750x500.jpeg","width":750,"height":500,"filesize":57584,"mime_type":"image\/jpeg","source_url":"https:\/\/hebdo24.com\/wp-content\/uploads\/2024\/07\/Les-400-Mawozo-incendient-le-commissariat-de-Ganthier-defiant-le-Gouvernement-et-la-PNH-750x500.jpeg"},"full":{"file":"Les-400-Mawozo-incendient-le-commissariat-de-Ganthier-defiant-le-Gouvernement-et-la-PNH.JPEG","width":1000,"height":666,"mime_type":"image\/jpeg","source_url":"https:\/\/hebdo24.com\/wp-content\/uploads\/2024\/07\/Les-400-Mawozo-incendient-le-commissariat-de-Ganthier-defiant-le-Gouvernement-et-la-PNH.JPEG"}},"image_meta":{"aperture":"0","credit":"phanordcbae","camera":"","caption":"","created_timestamp":"1721574949","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"1","keywords":[]}},"post":null,"source_url":"https:\/\/hebdo24.com\/wp-content\/uploads\/2024\/07\/Les-400-Mawozo-incendient-le-commissariat-de-Ganthier-defiant-le-Gouvernement-et-la-PNH.JPEG","_links":{"self":[{"href":"https:\/\/hebdo24.com\/en\/wp-json\/wp\/v2\/media\/20837","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hebdo24.com\/en\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/hebdo24.com\/en\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/hebdo24.com\/en\/wp-json\/wp\/v2\/users\/31"}],"replies":[{"embeddable":true,"href":"https:\/\/hebdo24.com\/en\/wp-json\/wp\/v2\/comments?post=20837"}]}}